{"id":22,"count":1,"description":"Los peces de acuario son animales dom\u00e9sticos populares debido a su belleza y facilidad de cuidado. Hay una amplia variedad de especies de peces que se pueden mantener en acuarios, como los peces dorados, los guppys y los bettas.","link":"https:\/\/animalesin.rebadise.com\/index.php\/category\/peces-de-acuario\/","name":"Peces de Acuario","slug":"peces-de-acuario","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Peces de Acuario archivos - animalesin.rebadise.com<\/title>\n<meta name=\"description\" content=\"Los peces de acuario son animales dom\u00e9sticos, los m\u00e1s populares debido a su belleza y facilidad de cuidado, son los peces dorados, los guppys y los bettas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/animalesin.rebadise.com\/index.php\/category\/peces-de-acuario\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peces de Acuario archivos - animalesin.rebadise.com\" \/>\n<meta property=\"og:description\" content=\"Los peces de acuario son animales dom\u00e9sticos, los m\u00e1s populares debido a su belleza y facilidad de cuidado, son los peces dorados, los guppys y los bettas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/animalesin.rebadise.com\/index.php\/category\/peces-de-acuario\/\" \/>\n<meta property=\"og:site_name\" content=\"animalesin.rebadise.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/animalesin.rebadise.com\/index.php\/category\/peces-de-acuario\/\",\"url\":\"https:\/\/animalesin.rebadise.com\/index.php\/category\/peces-de-acuario\/\",\"name\":\"Peces de Acuario archivos - animalesin.rebadise.com\",\"isPartOf\":{\"@id\":\"https:\/\/animalesin.rebadise.com\/#website\"},\"description\":\"Los peces de acuario son animales dom\u00e9sticos, los m\u00e1s populares debido a su belleza y facilidad de cuidado, son los peces dorados, los guppys y los bettas.\",\"breadcrumb\":{\"@id\":\"https:\/\/animalesin.rebadise.com\/index.php\/category\/peces-de-acuario\/#breadcrumb\"},\"inLanguage\":\"es-CR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/animalesin.rebadise.com\/index.php\/category\/peces-de-acuario\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/animalesin.rebadise.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peces de Acuario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/animalesin.rebadise.com\/#website\",\"url\":\"https:\/\/animalesin.rebadise.com\/\",\"name\":\"animalesin.rebadise.com\",\"description\":\"Animales dom\u00e9sticos y silvestres\",\"publisher\":{\"@id\":\"https:\/\/animalesin.rebadise.com\/#\/schema\/person\/d00120a702f9005ac7ad9d780a08f497\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/animalesin.rebadise.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-CR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/animalesin.rebadise.com\/#\/schema\/person\/d00120a702f9005ac7ad9d780a08f497\",\"name\":\"animalesin.rebadise.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CR\",\"@id\":\"https:\/\/animalesin.rebadise.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/animalesin.rebadise.com\/wp-content\/uploads\/2023\/06\/LOGO-Animales-In-e1687382741724.png\",\"contentUrl\":\"https:\/\/animalesin.rebadise.com\/wp-content\/uploads\/2023\/06\/LOGO-Animales-In-e1687382741724.png\",\"width\":700,\"height\":214,\"caption\":\"animalesin.rebadise.com\"},\"logo\":{\"@id\":\"https:\/\/animalesin.rebadise.com\/#\/schema\/person\/image\/\"},\"sameAs\":[\"http:\/\/animalesin.rebadise.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peces de Acuario archivos - animalesin.rebadise.com","description":"Los peces de acuario son animales dom\u00e9sticos, los m\u00e1s populares debido a su belleza y facilidad de cuidado, son los peces dorados, los guppys y los bettas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/animalesin.rebadise.com\/index.php\/category\/peces-de-acuario\/","og_locale":"es_ES","og_type":"article","og_title":"Peces de Acuario archivos - animalesin.rebadise.com","og_description":"Los peces de acuario son animales dom\u00e9sticos, los m\u00e1s populares debido a su belleza y facilidad de cuidado, son los peces dorados, los guppys y los bettas.","og_url":"https:\/\/animalesin.rebadise.com\/index.php\/category\/peces-de-acuario\/","og_site_name":"animalesin.rebadise.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/animalesin.rebadise.com\/index.php\/category\/peces-de-acuario\/","url":"https:\/\/animalesin.rebadise.com\/index.php\/category\/peces-de-acuario\/","name":"Peces de Acuario archivos - animalesin.rebadise.com","isPartOf":{"@id":"https:\/\/animalesin.rebadise.com\/#website"},"description":"Los peces de acuario son animales dom\u00e9sticos, los m\u00e1s populares debido a su belleza y facilidad de cuidado, son los peces dorados, los guppys y los bettas.","breadcrumb":{"@id":"https:\/\/animalesin.rebadise.com\/index.php\/category\/peces-de-acuario\/#breadcrumb"},"inLanguage":"es-CR"},{"@type":"BreadcrumbList","@id":"https:\/\/animalesin.rebadise.com\/index.php\/category\/peces-de-acuario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/animalesin.rebadise.com\/"},{"@type":"ListItem","position":2,"name":"Peces de Acuario"}]},{"@type":"WebSite","@id":"https:\/\/animalesin.rebadise.com\/#website","url":"https:\/\/animalesin.rebadise.com\/","name":"animalesin.rebadise.com","description":"Animales dom\u00e9sticos y silvestres","publisher":{"@id":"https:\/\/animalesin.rebadise.com\/#\/schema\/person\/d00120a702f9005ac7ad9d780a08f497"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/animalesin.rebadise.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-CR"},{"@type":["Person","Organization"],"@id":"https:\/\/animalesin.rebadise.com\/#\/schema\/person\/d00120a702f9005ac7ad9d780a08f497","name":"animalesin.rebadise.com","image":{"@type":"ImageObject","inLanguage":"es-CR","@id":"https:\/\/animalesin.rebadise.com\/#\/schema\/person\/image\/","url":"https:\/\/animalesin.rebadise.com\/wp-content\/uploads\/2023\/06\/LOGO-Animales-In-e1687382741724.png","contentUrl":"https:\/\/animalesin.rebadise.com\/wp-content\/uploads\/2023\/06\/LOGO-Animales-In-e1687382741724.png","width":700,"height":214,"caption":"animalesin.rebadise.com"},"logo":{"@id":"https:\/\/animalesin.rebadise.com\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/animalesin.rebadise.com"]}]}},"_links":{"self":[{"href":"https:\/\/animalesin.rebadise.com\/index.php\/wp-json\/wp\/v2\/categories\/22"}],"collection":[{"href":"https:\/\/animalesin.rebadise.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/animalesin.rebadise.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/animalesin.rebadise.com\/index.php\/wp-json\/wp\/v2\/posts?categories=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}